{"id":26400,"date":"2019-07-10T10:00:25","date_gmt":"2019-07-10T08:00:25","guid":{"rendered":"https:\/\/www.csl.lu\/vos-droits\/salaries\/duree-du-travail\/femmes-enceintes\/"},"modified":"2023-07-11T09:35:14","modified_gmt":"2023-07-11T07:35:14","slug":"pregnancies","status":"publish","type":"page","link":"https:\/\/www.csl.lu\/en\/your-rights\/employees\/working-time\/pregnancies\/","title":{"rendered":"Pregnancies"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":26278,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"template-content_multi_table.php","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","footnotes":""},"class_list":["post-26400","page","type-page","status-publish","hentry","page_site-csl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pregnancies - Chambre des salari\u00e9s - CSL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csl.lu\/en\/your-rights\/employees\/working-time\/pregnancies\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pregnancies - Chambre des salari\u00e9s - CSL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csl.lu\/en\/your-rights\/employees\/working-time\/pregnancies\/\" \/>\n<meta property=\"og:site_name\" content=\"Chambre des salari\u00e9s - CSL\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-11T07:35:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.csl.lu\/app\/uploads\/2020\/03\/adobestock_256059256-scaled.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.csl.lu\/app\/uploads\/2020\/03\/adobestock_256059256-scaled.jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.csl.lu\\\/en\\\/your-rights\\\/employees\\\/working-time\\\/pregnancies\\\/\",\"url\":\"https:\\\/\\\/www.csl.lu\\\/en\\\/your-rights\\\/employees\\\/working-time\\\/pregnancies\\\/\",\"name\":\"Pregnancies - Chambre des salari\u00e9s - CSL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/#website\"},\"datePublished\":\"2019-07-10T08:00:25+00:00\",\"dateModified\":\"2023-07-11T07:35:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.csl.lu\\\/en\\\/your-rights\\\/employees\\\/working-time\\\/pregnancies\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.csl.lu\\\/en\\\/your-rights\\\/employees\\\/working-time\\\/pregnancies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.csl.lu\\\/en\\\/your-rights\\\/employees\\\/working-time\\\/pregnancies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.csl.lu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Your rights\",\"item\":\"https:\\\/\\\/www.csl.lu\\\/en\\\/your-rights\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Employees\",\"item\":\"https:\\\/\\\/www.csl.lu\\\/en\\\/your-rights\\\/employees\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Working time\",\"item\":\"https:\\\/\\\/www.csl.lu\\\/en\\\/your-rights\\\/employees\\\/working-time\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Pregnancies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/\",\"name\":\"Chambre des salari\u00e9s - CSL\",\"description\":\"La CSL d\u00e9fend les int\u00e9r\u00eats des salari\u00e9s et des retrait\u00e9s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pregnancies - Chambre des salari\u00e9s - CSL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csl.lu\/en\/your-rights\/employees\/working-time\/pregnancies\/","og_locale":"en_US","og_type":"article","og_title":"Pregnancies - Chambre des salari\u00e9s - CSL","og_url":"https:\/\/www.csl.lu\/en\/your-rights\/employees\/working-time\/pregnancies\/","og_site_name":"Chambre des salari\u00e9s - CSL","article_modified_time":"2023-07-11T07:35:14+00:00","og_image":[{"url":"https:\/\/www.csl.lu\/app\/uploads\/2020\/03\/adobestock_256059256-scaled.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.csl.lu\/app\/uploads\/2020\/03\/adobestock_256059256-scaled.jpeg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csl.lu\/en\/your-rights\/employees\/working-time\/pregnancies\/","url":"https:\/\/www.csl.lu\/en\/your-rights\/employees\/working-time\/pregnancies\/","name":"Pregnancies - Chambre des salari\u00e9s - CSL","isPartOf":{"@id":"https:\/\/www.csl.lu\/fr\/#website"},"datePublished":"2019-07-10T08:00:25+00:00","dateModified":"2023-07-11T07:35:14+00:00","breadcrumb":{"@id":"https:\/\/www.csl.lu\/en\/your-rights\/employees\/working-time\/pregnancies\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csl.lu\/en\/your-rights\/employees\/working-time\/pregnancies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.csl.lu\/en\/your-rights\/employees\/working-time\/pregnancies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.csl.lu\/en\/"},{"@type":"ListItem","position":2,"name":"Your rights","item":"https:\/\/www.csl.lu\/en\/your-rights\/"},{"@type":"ListItem","position":3,"name":"Employees","item":"https:\/\/www.csl.lu\/en\/your-rights\/employees\/"},{"@type":"ListItem","position":4,"name":"Working time","item":"https:\/\/www.csl.lu\/en\/your-rights\/employees\/working-time\/"},{"@type":"ListItem","position":5,"name":"Pregnancies"}]},{"@type":"WebSite","@id":"https:\/\/www.csl.lu\/fr\/#website","url":"https:\/\/www.csl.lu\/fr\/","name":"Chambre des salari\u00e9s - CSL","description":"La CSL d\u00e9fend les int\u00e9r\u00eats des salari\u00e9s et des retrait\u00e9s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csl.lu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.csl.lu\/en\/wp-json\/wp\/v2\/pages\/26400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csl.lu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.csl.lu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.csl.lu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csl.lu\/en\/wp-json\/wp\/v2\/comments?post=26400"}],"version-history":[{"count":2,"href":"https:\/\/www.csl.lu\/en\/wp-json\/wp\/v2\/pages\/26400\/revisions"}],"predecessor-version":[{"id":79707,"href":"https:\/\/www.csl.lu\/en\/wp-json\/wp\/v2\/pages\/26400\/revisions\/79707"}],"up":[{"embeddable":true,"href":"https:\/\/www.csl.lu\/en\/wp-json\/wp\/v2\/pages\/26278"}],"wp:attachment":[{"href":"https:\/\/www.csl.lu\/en\/wp-json\/wp\/v2\/media?parent=26400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}