{"id":42,"date":"2019-07-05T15:01:46","date_gmt":"2019-07-05T13:01:46","guid":{"rendered":"https:\/\/www.csl.lu\/?page_id=42"},"modified":"2025-08-14T15:56:21","modified_gmt":"2025-08-14T13:56:21","slug":"commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement","status":"publish","type":"page","link":"https:\/\/www.csl.lu\/fr\/csl\/structure\/commissions-internes\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\/","title":{"rendered":"Commission aux affaires sociales, s\u00e9curit\u00e9 et sant\u00e9 au travail et environnement"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":35,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"template-membre_assemble_pleniere.php","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","footnotes":""},"class_list":["post-42","page","type-page","status-publish","hentry","page_site-csl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Commission aux affaires sociales, s\u00e9curit\u00e9 et sant\u00e9 au travail et environnement - Chambre des salari\u00e9s - CSL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csl.lu\/fr\/csl\/structure\/commissions-internes\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Commission aux affaires sociales, s\u00e9curit\u00e9 et sant\u00e9 au travail et environnement - Chambre des salari\u00e9s - CSL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csl.lu\/fr\/csl\/structure\/commissions-internes\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\/\" \/>\n<meta property=\"og:site_name\" content=\"Chambre des salari\u00e9s - CSL\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-14T13:56:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.csl.lu\/app\/uploads\/2020\/03\/adobestock_78607523-scaled.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.csl.lu\/app\/uploads\/2020\/03\/adobestock_78607523-scaled.jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/csl\\\/structure\\\/commissions-internes\\\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\\\/\",\"url\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/csl\\\/structure\\\/commissions-internes\\\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\\\/\",\"name\":\"Commission aux affaires sociales, s\u00e9curit\u00e9 et sant\u00e9 au travail et environnement - Chambre des salari\u00e9s - CSL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/#website\"},\"datePublished\":\"2019-07-05T13:01:46+00:00\",\"dateModified\":\"2025-08-14T13:56:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/csl\\\/structure\\\/commissions-internes\\\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.csl.lu\\\/fr\\\/csl\\\/structure\\\/commissions-internes\\\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/csl\\\/structure\\\/commissions-internes\\\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CSL\",\"item\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/csl\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Structure\",\"item\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/csl\\\/structure\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Commissions internes\",\"item\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/csl\\\/structure\\\/commissions-internes\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Commission aux affaires sociales, s\u00e9curit\u00e9 et sant\u00e9 au travail et environnement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/\",\"name\":\"Chambre des salari\u00e9s - CSL\",\"description\":\"La CSL d\u00e9fend les int\u00e9r\u00eats des salari\u00e9s et des retrait\u00e9s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.csl.lu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Commission aux affaires sociales, s\u00e9curit\u00e9 et sant\u00e9 au travail et environnement - Chambre des salari\u00e9s - CSL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csl.lu\/fr\/csl\/structure\/commissions-internes\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\/","og_locale":"fr_FR","og_type":"article","og_title":"Commission aux affaires sociales, s\u00e9curit\u00e9 et sant\u00e9 au travail et environnement - Chambre des salari\u00e9s - CSL","og_url":"https:\/\/www.csl.lu\/fr\/csl\/structure\/commissions-internes\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\/","og_site_name":"Chambre des salari\u00e9s - CSL","article_modified_time":"2025-08-14T13:56:21+00:00","og_image":[{"url":"https:\/\/www.csl.lu\/app\/uploads\/2020\/03\/adobestock_78607523-scaled.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.csl.lu\/app\/uploads\/2020\/03\/adobestock_78607523-scaled.jpeg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csl.lu\/fr\/csl\/structure\/commissions-internes\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\/","url":"https:\/\/www.csl.lu\/fr\/csl\/structure\/commissions-internes\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\/","name":"Commission aux affaires sociales, s\u00e9curit\u00e9 et sant\u00e9 au travail et environnement - Chambre des salari\u00e9s - CSL","isPartOf":{"@id":"https:\/\/www.csl.lu\/fr\/#website"},"datePublished":"2019-07-05T13:01:46+00:00","dateModified":"2025-08-14T13:56:21+00:00","breadcrumb":{"@id":"https:\/\/www.csl.lu\/fr\/csl\/structure\/commissions-internes\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csl.lu\/fr\/csl\/structure\/commissions-internes\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.csl.lu\/fr\/csl\/structure\/commissions-internes\/commission-aux-affaires-sociales-securite-et-sante-au-travail-et-environnement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.csl.lu\/fr\/"},{"@type":"ListItem","position":2,"name":"CSL","item":"https:\/\/www.csl.lu\/fr\/csl\/"},{"@type":"ListItem","position":3,"name":"Structure","item":"https:\/\/www.csl.lu\/fr\/csl\/structure\/"},{"@type":"ListItem","position":4,"name":"Commissions internes","item":"https:\/\/www.csl.lu\/fr\/csl\/structure\/commissions-internes\/"},{"@type":"ListItem","position":5,"name":"Commission aux affaires sociales, s\u00e9curit\u00e9 et sant\u00e9 au travail et environnement"}]},{"@type":"WebSite","@id":"https:\/\/www.csl.lu\/fr\/#website","url":"https:\/\/www.csl.lu\/fr\/","name":"Chambre des salari\u00e9s - CSL","description":"La CSL d\u00e9fend les int\u00e9r\u00eats des salari\u00e9s et des retrait\u00e9s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csl.lu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.csl.lu\/fr\/wp-json\/wp\/v2\/pages\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csl.lu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.csl.lu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.csl.lu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csl.lu\/fr\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":6,"href":"https:\/\/www.csl.lu\/fr\/wp-json\/wp\/v2\/pages\/42\/revisions"}],"predecessor-version":[{"id":115713,"href":"https:\/\/www.csl.lu\/fr\/wp-json\/wp\/v2\/pages\/42\/revisions\/115713"}],"up":[{"embeddable":true,"href":"https:\/\/www.csl.lu\/fr\/wp-json\/wp\/v2\/pages\/35"}],"wp:attachment":[{"href":"https:\/\/www.csl.lu\/fr\/wp-json\/wp\/v2\/media?parent=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}